{"id":33509,"date":"2023-07-13T07:28:57","date_gmt":"2023-07-13T07:28:57","guid":{"rendered":"https:\/\/new.spyder.datacolor.eu\/spyder\/prodotti\/spyder-x-elite\/"},"modified":"2024-02-08T08:13:46","modified_gmt":"2024-02-08T08:13:46","slug":"spyder-x-elite","status":"publish","type":"page","link":"https:\/\/www.datacolor.com\/spyder\/it\/prodotti\/spyder-x-elite\/","title":{"rendered":"Spyder X Elite"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column width=&#8221;3\/5&#8243;][vc_empty_space][vc_gallery interval=&#8221;3&#8243; images=&#8221;31387,31397,31407,31417,31427,31437,31447,31457&#8243; img_size=&#8221;750&#215;500&#8243; el_class=&#8221;product_images&#8221;][vc_empty_space][\/vc_column][vc_column width=&#8221;2\/5&#8243;][vc_column_text]<\/p>\n<h1 class=\"mainheader\">Spyder X Elite<\/h1>\n<h2 class=\"subheader\">Strumento di calibrazione del colore per monitor di editing fotografico e video con strumenti di analisi completi.<br \/>\n<em>Nota: non adattabile alla piattaforma Spyder X2.<\/em><br \/>\n<div id="getprice-banner-sxe100"></div><\/h2>\n<p>[\/vc_column_text][vc_empty_space]\r\n\t\t\t<div class=\"nm_btn_align_left\">\r\n\t\t\t\t<a href=\"https:\/\/goto.datacolor.com\/webshop\/buynow\/sxe100\" class=\"nm_btn nm_btn_md nm_btn_filled\" title=\"Acquista Spyder X Pro\">\r\n\t\t\t\t\t<span class=\"nm_btn_title\">Aggiungi al carrello<\/span>\r\n\t\t\t\t\t<span class=\"nm_btn_bg\" style=\"background-color:#dd3333;\"><\/span>\r\n\t\t\t\t<\/a>\r\n\t\t\t<\/div>[vc_empty_space][\/vc_column][\/vc_row][vc_row][vc_column]<div id=\"advanced-tabs-desc-wrap-1429\" class=\"ult_tabs \" style=\" \" data-tabsstyle=\"style2\"\n data-titlebg=\"#ebebeb\" data-titlecolor=\"#666666\" data-fullheight=\"off\"\n data-titlehoverbg=\"#dcdcdc\" data-titlehovercolor=\"#666666\"\n data-rotatetabs=\"0\" data-responsivemode=\"Both\" data-animation=\"Fade\"\ndata-activetitle=\"#666666\" data-activeicon=\"\" data-activebg=\"#f8f8f8\"  data-respmode=\"Tabs\" data-respwidth=\"400\" data-scroll = \"on\" data-activeindex=\"1\"><ul id=advanced-tabs-wrap-3750 class=\"ult_tabmenu style2 \" style=\"color:transparent;border-bottom-color:transparent;border-bottom-width:0px;border-bottom-style:solid;border-bottom-width:0px;\"><li class=\"ult_tab_li  \" data-iconcolor=\"#74777b\" data-iconhover=\"#ffffff\" style=\"\">\n\t\t\t\t\t<a href=\"#1679579937154-2-8\"  id=\"1679579937154-2-8\"  style=\"color:#666666;background-color:#ebebeb;border-top-left-radius:3px;;   \" class=\"ult_a  \">\n\t\t\t\t\t     <span class=\"ult_tab_main Both \">\n\t\t\t\t\t \t\t <span class=\"ult_tab_section\">\n\t\t\t\t\t   \t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-3750 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_tab_display_text ult-responsive\" style=\";\">Info<\/span>\n\t\t\t\t\t   \t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/li><li class=\"ult_tab_li  \" data-iconcolor=\"#74777b\" data-iconhover=\"#ffffff\" style=\"\">\n\t\t\t\t\t<a href=\"#1679487018506-8\"  id=\"1679487018506-8\"  style=\"color:#666666;background-color:#ebebeb;;   \" class=\"ult_a  \">\n\t\t\t\t\t     <span class=\"ult_tab_main Both \">\n\t\t\t\t\t \t\t <span class=\"ult_tab_section\">\n\t\t\t\t\t   \t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-3750 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_tab_display_text ult-responsive\" style=\";\">Specifiche tecniche<\/span>\n\t\t\t\t\t   \t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/li><li class=\"ult_tab_li  \" data-iconcolor=\"#74777b\" data-iconhover=\"#ffffff\" style=\"\">\n\t\t\t\t\t<a href=\"#1679487018516-5\"  id=\"1679487018516-5\"  style=\"color:#666666;background-color:#ebebeb;border-top-right-radius:3px;;   \" class=\"ult_a  \">\n\t\t\t\t\t     <span class=\"ult_tab_main Both \">\n\t\t\t\t\t \t\t <span class=\"ult_tab_section\">\n\t\t\t\t\t   \t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-3750 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_tab_display_text ult-responsive\" style=\";\">Guide per l&apos;utente e avvio rapido<\/span>\n\t\t\t\t\t   \t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/li><\/ul><div  data-ultimate-target='#advanced-tabs-desc-wrap-1429 .ult_tabcontent .ult_tab_min_contain  p'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}' class=\"ult_tabcontent ult-responsive style2\" style=\"background-color:#f8f8f8;color:#74777b;\"><div class=\"ult_tab_min_contain \" >\n\t\t\t<div  class=\"ult_tabitemname\"  >\n\t\t\t\t[vc_column_text css=&#8221;.vc_custom_1688635257446{padding-top: 30px !important;padding-right: 15px !important;padding-bottom: 60px !important;padding-left: 15px !important;}&#8221;]<\/p>\n<ul>\n<li>Il motore del colore basato sulla lente offre un livello superiore di precisione del colore, destinato all&#8217;uso con un computer con un solo monitor, anche se \u00e8 possibile creare profili di colore per pi\u00f9 display in base alla capacit\u00e0 LUT del computer. Spyder X Elite \u00e8 dotato di monitoraggio della luce ambientale, cambio automatico del profilo e precisione del colore dello schermo, dei dettagli delle ombre e del bilanciamento del bianco.<\/li>\n<li>La calibrazione rapida e semplice con un solo clic e il flusso di lavoro guidato con 12 target di calibrazione predefiniti per una precisione del colore avanzata.<\/li>\n<li>La funzionalit\u00e0 SpyderProof fornisce una valutazione del display prima e dopo l&#8217;installazione e consente di vedere la differenza utilizzando le proprie immagini.<\/li>\n<li>Spyder X Elite \u00e8 pienamente supportato da Windows 7 32\/64 e oltre e da Mac OS X 10.10 e oltre. La risoluzione del monitor deve essere pari o superiore a 1280\u00d7768, \u00e8 necessaria una scheda video a 16 bit (si consiglia 24 bit), 1 GB di RAM disponibile e 500 MB di disco rigido disponibile. \u00c8 inoltre necessaria una connessione a Internet per il download del software.<\/li>\n<\/ul>\n<p>[\/vc_column_text]\n\t\t\t<\/div>\n\t\t\t<div  class=\"ult_tabitemname\"  >\n\t\t\t\t[vc_row_inner css=&#8221;.vc_custom_1679580699165{padding-top: 30px !important;padding-right: 15px !important;padding-bottom: 60px !important;padding-left: 15px !important;}&#8221;][vc_column_inner width=&#8221;2\/3&#8243;][vc_column_text]<\/p>\n<h4>COSA C&#8217;\u00c8 NELLA SCATOLA<\/h4>\n<ul>\n<li>Sensore Spyder X<\/li>\n<li>Scheda di benvenuto con link al download del software e informazioni sulla garanzia<\/li>\n<li>Numero di serie univoco per attivare il software<\/li>\n<li>Link alle dimostrazioni online, alla guida utente, ai video e all&#8217;assistenza.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h4>REQUISITI DI SISTEMA<\/h4>\n<ul>\n<li>Windows 10 32\/64, Windows 11<\/li>\n<li>Mac OS X 10.10 e versioni successive<\/li>\n<li>Risoluzione del monitor 1280&#215;768 o superiore, scheda video a 16 bit (consigliata a 24 bit), 1 GB di RAM disponibile, 500 MB di disco rigido disponibile<\/li>\n<li>Connessione a Internet per il download del software<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h4>LINGUE SUPPORTATE<\/h4>\n<p>Inglese, francese, italiano, tedesco, spagnolo, russo, giapponese, cinese semplice, cinese tradizionale, coreano<\/p>\n<p>&nbsp;<\/p>\n<h4>TECNOLOGIE DI VISUALIZZAZIONE SUPPORTATE<\/h4>\n<p>Supporta i tipi di display pi\u00f9 moderni.<\/p>\n<p><u>Nota:<\/u> con la crescente diffusione degli OLED, anche i diversi tipi di display OLED sono diventati pi\u00f9 diffusi. Sebbene sia possibile utilizzare Spyder X\/X2 per calibrare alcuni tipi di display OLED, non possiamo garantire l&#8217;accuratezza della calibrazione risultante. Attualmente, non consigliamo di utilizzare Spyder X\/X2 per calibrare alcun tipo di display OLED per applicazioni critiche dal punto di vista cromatico.<\/p>\n<p>&nbsp;<\/p>\n<h4>PROTOCOLLI USB SUPPORTATI<\/h4>\n<ul>\n<li>USB 1.1, USB 2.x e USB 3.x<\/li>\n<li>Spina USB A, compatibile anche con gli adattatori USB A&gt;C da utilizzare nelle porte USB C<\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_single_image image=&#8221;14183&#8243; img_size=&#8221;large&#8221; alignment=&#8221;center&#8221;][\/vc_column_inner][\/vc_row_inner]\n\t\t\t<\/div>\n\t\t\t<div  class=\"ult_tabitemname\"  >\n\t\t\t\t[vc_row_inner css=&#8221;.vc_custom_1679580717308{padding-top: 30px !important;padding-right: 15px !important;padding-bottom: 60px !important;padding-left: 15px !important;}&#8221;][vc_column_inner]\r\n\t\t\t<div class=\"nm_btn_align_left\">\r\n\t\t\t\t<a href=\"https:\/\/www.datacolor.com\/spyder\/wp-content\/uploads\/2023\/04\/SpyderX-Users-Guide-FINAL-EN.pdf\" class=\"nm_btn nm_btn_md nm_btn_filled\">\r\n\t\t\t\t\t<span class=\"nm_btn_title\">Scarica la Guida per l&amp;apos;utente<\/span>\r\n\t\t\t\t\t<span class=\"nm_btn_bg\" style=\"background-color:#dd3333;\"><\/span>\r\n\t\t\t\t<\/a>\r\n\t\t\t<\/div>\r\n\t\t\t<div class=\"nm_btn_align_left\">\r\n\t\t\t\t<a href=\"https:\/\/www.datacolor.com\/spyder\/wp-content\/uploads\/2023\/04\/SpyderX-QSG-FINAL-EN.pdf\" class=\"nm_btn nm_btn_md nm_btn_filled\">\r\n\t\t\t\t\t<span class=\"nm_btn_title\">Guida rapida<\/span>\r\n\t\t\t\t\t<span class=\"nm_btn_bg\" style=\"background-color:#dd3333;\"><\/span>\r\n\t\t\t\t<\/a>\r\n\t\t\t<\/div>[\/vc_column_inner][\/vc_row_inner]\n\t\t\t<\/div><\/div><\/div><\/div><div class=\"ult_acord advanced-tabs-desc-wrap-1429\">\n   <div class=\"ult-tabto-accordion \" style=\"width:;\"\n    data-titlecolor=\"#666666\"  data-titlebg=\"#ebebeb\"\n     data-titlehoverbg=\"#dcdcdc\" data-titlehovercolor=\"#666666\" data-animation=\"Fade\"\n     data-activetitle=\"#666666\" data-activeicon=\"\" data-activebg=\"#f8f8f8\" data-scroll = \"on\" data-activeindex=\"1\" >\n     <dl><dt class=\"\">\n\t        \t<a class=\"ult-tabto-actitle withBorder ult_a \" id=\"1679579937154-2-8\" style=\"color:#666666;;background-color:#ebebeb;border-bottom-color:transparent;border-bottom-width:0px;border-bottom-style:solid;\" href=\"#1679579937154-2-8\">\n\t        \t\t<i class=\"accordion-icon\"><\/i>\n\t        \t\t\t<span class=\"ult_tab_main ult_ac_main ult_noacordicnBoth\">\n\n\t\t\t\t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-3750 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_acordian-text ult-responsive\" style=\";color:inherit \" >Info<\/span>\n\t\t\t\t\t\t<\/span><\/a><\/dt>\n\t            \t\t<dd class=\"ult-tabto-accordionItem ult-tabto-accolapsed\">\n\t\t\t\t            <div class=\"ult-tabto-acontent\" style=\"background-color:#f8f8f8;color:#74777b;\">\n\t\t\t\t               [vc_column_text css=&#8221;.vc_custom_1688635257446{padding-top: 30px !important;padding-right: 15px !important;padding-bottom: 60px !important;padding-left: 15px !important;}&#8221;]<\/p>\n<ul>\n<li>Il motore del colore basato sulla lente offre un livello superiore di precisione del colore, destinato all&#8217;uso con un computer con un solo monitor, anche se \u00e8 possibile creare profili di colore per pi\u00f9 display in base alla capacit\u00e0 LUT del computer. Spyder X Elite \u00e8 dotato di monitoraggio della luce ambientale, cambio automatico del profilo e precisione del colore dello schermo, dei dettagli delle ombre e del bilanciamento del bianco.<\/li>\n<li>La calibrazione rapida e semplice con un solo clic e il flusso di lavoro guidato con 12 target di calibrazione predefiniti per una precisione del colore avanzata.<\/li>\n<li>La funzionalit\u00e0 SpyderProof fornisce una valutazione del display prima e dopo l&#8217;installazione e consente di vedere la differenza utilizzando le proprie immagini.<\/li>\n<li>Spyder X Elite \u00e8 pienamente supportato da Windows 7 32\/64 e oltre e da Mac OS X 10.10 e oltre. La risoluzione del monitor deve essere pari o superiore a 1280\u00d7768, \u00e8 necessaria una scheda video a 16 bit (si consiglia 24 bit), 1 GB di RAM disponibile e 500 MB di disco rigido disponibile. \u00c8 inoltre necessaria una connessione a Internet per il download del software.<\/li>\n<\/ul>\n<p>[\/vc_column_text]\n\t\t\t\t            <\/div>\n\t        \t\t\t<\/dd><dt class=\"\">\n\t        \t<a class=\"ult-tabto-actitle withBorder ult_a \" id=\"1679487018506-8\" style=\"color:#666666;;background-color:#ebebeb;border-bottom-color:transparent;border-bottom-width:0px;border-bottom-style:solid;border-bottom-color:transparent;border-bottom-width:0px;border-bottom-style:solid;\" href=\"#1679487018506-8\">\n\t        \t\t<i class=\"accordion-icon\"><\/i>\n\t        \t\t\t<span class=\"ult_tab_main ult_ac_main ult_noacordicnBoth\">\n\n\t\t\t\t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-3750 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_acordian-text ult-responsive\" style=\";color:inherit \" >Specifiche tecniche<\/span>\n\t\t\t\t\t\t<\/span><\/a><\/dt>\n\t            \t\t<dd class=\"ult-tabto-accordionItem ult-tabto-accolapsed\">\n\t\t\t\t            <div class=\"ult-tabto-acontent\" style=\"background-color:#f8f8f8;color:#74777b;\">\n\t\t\t\t               [vc_row_inner css=&#8221;.vc_custom_1679580699165{padding-top: 30px !important;padding-right: 15px !important;padding-bottom: 60px !important;padding-left: 15px !important;}&#8221;][vc_column_inner width=&#8221;2\/3&#8243;][vc_column_text]<\/p>\n<h4>COSA C&#8217;\u00c8 NELLA SCATOLA<\/h4>\n<ul>\n<li>Sensore Spyder X<\/li>\n<li>Scheda di benvenuto con link al download del software e informazioni sulla garanzia<\/li>\n<li>Numero di serie univoco per attivare il software<\/li>\n<li>Link alle dimostrazioni online, alla guida utente, ai video e all&#8217;assistenza.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h4>REQUISITI DI SISTEMA<\/h4>\n<ul>\n<li>Windows 10 32\/64, Windows 11<\/li>\n<li>Mac OS X 10.10 e versioni successive<\/li>\n<li>Risoluzione del monitor 1280&#215;768 o superiore, scheda video a 16 bit (consigliata a 24 bit), 1 GB di RAM disponibile, 500 MB di disco rigido disponibile<\/li>\n<li>Connessione a Internet per il download del software<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h4>LINGUE SUPPORTATE<\/h4>\n<p>Inglese, francese, italiano, tedesco, spagnolo, russo, giapponese, cinese semplice, cinese tradizionale, coreano<\/p>\n<p>&nbsp;<\/p>\n<h4>TECNOLOGIE DI VISUALIZZAZIONE SUPPORTATE<\/h4>\n<p>Supporta i tipi di display pi\u00f9 moderni.<\/p>\n<p><u>Nota:<\/u> con la crescente diffusione degli OLED, anche i diversi tipi di display OLED sono diventati pi\u00f9 diffusi. Sebbene sia possibile utilizzare Spyder X\/X2 per calibrare alcuni tipi di display OLED, non possiamo garantire l&#8217;accuratezza della calibrazione risultante. Attualmente, non consigliamo di utilizzare Spyder X\/X2 per calibrare alcun tipo di display OLED per applicazioni critiche dal punto di vista cromatico.<\/p>\n<p>&nbsp;<\/p>\n<h4>PROTOCOLLI USB SUPPORTATI<\/h4>\n<ul>\n<li>USB 1.1, USB 2.x e USB 3.x<\/li>\n<li>Spina USB A, compatibile anche con gli adattatori USB A&gt;C da utilizzare nelle porte USB C<\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_single_image image=&#8221;14183&#8243; img_size=&#8221;large&#8221; alignment=&#8221;center&#8221;][\/vc_column_inner][\/vc_row_inner]\n\t\t\t\t            <\/div>\n\t        \t\t\t<\/dd><dt class=\"\">\n\t        \t<a class=\"ult-tabto-actitle withBorder ult_a \" id=\"1679487018516-5\" style=\"color:#666666;;background-color:#ebebeb;border-bottom-color:transparent;border-bottom-width:0px;border-bottom-style:solid;border-bottom-color:transparent;border-bottom-width:0px;border-bottom-style:solid;border-bottom-color:transparent;border-bottom-width:0px;border-bottom-style:solid;\" href=\"#1679487018516-5\">\n\t        \t\t<i class=\"accordion-icon\"><\/i>\n\t        \t\t\t<span class=\"ult_tab_main ult_ac_main ult_noacordicnBoth\">\n\n\t\t\t\t\t\t<span  data-ultimate-target='#advanced-tabs-wrap-3750 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text no_icon ult_acordian-text ult-responsive\" style=\";color:inherit \" >Guide per l&apos;utente e avvio rapido<\/span>\n\t\t\t\t\t\t<\/span><\/a><\/dt>\n\t            \t\t<dd class=\"ult-tabto-accordionItem ult-tabto-accolapsed\">\n\t\t\t\t            <div class=\"ult-tabto-acontent\" style=\"background-color:#f8f8f8;color:#74777b;\">\n\t\t\t\t               [vc_row_inner css=&#8221;.vc_custom_1679580717308{padding-top: 30px !important;padding-right: 15px !important;padding-bottom: 60px !important;padding-left: 15px !important;}&#8221;][vc_column_inner]\r\n\t\t\t<div class=\"nm_btn_align_left\">\r\n\t\t\t\t<a href=\"https:\/\/www.datacolor.com\/spyder\/wp-content\/uploads\/2023\/04\/SpyderX-Users-Guide-FINAL-EN.pdf\" class=\"nm_btn nm_btn_md nm_btn_filled\">\r\n\t\t\t\t\t<span class=\"nm_btn_title\">Scarica la Guida per l&amp;apos;utente<\/span>\r\n\t\t\t\t\t<span class=\"nm_btn_bg\" style=\"background-color:#dd3333;\"><\/span>\r\n\t\t\t\t<\/a>\r\n\t\t\t<\/div>\r\n\t\t\t<div class=\"nm_btn_align_left\">\r\n\t\t\t\t<a href=\"https:\/\/www.datacolor.com\/spyder\/wp-content\/uploads\/2023\/04\/SpyderX-QSG-FINAL-EN.pdf\" class=\"nm_btn nm_btn_md nm_btn_filled\">\r\n\t\t\t\t\t<span class=\"nm_btn_title\">Guida rapida<\/span>\r\n\t\t\t\t\t<span class=\"nm_btn_bg\" style=\"background-color:#dd3333;\"><\/span>\r\n\t\t\t\t<\/a>\r\n\t\t\t<\/div>[\/vc_column_inner][\/vc_row_inner]\n\t\t\t\t            <\/div>\n\t        \t\t\t<\/dd>\n    \t<\/dl>\n    <!--<div class=\"extraborder\" style=\"background-color:#dcdcdc\"><\/div>-->\n<\/div>\n\n<\/div>[vc_empty_space][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1679489540798{padding-top: 30px !important;padding-bottom: 30px !important;}&#8221;][vc_column][vc_column_text]<\/p>\n<h2>Sappiamo che ci vuole molto per ottenere lo scatto perfetto.<\/h2>\n<p>[\/vc_column_text][vc_empty_space][vc_row_inner][vc_column_inner width=&#8221;3\/5&#8243;][vc_single_image image=&#8221;14200&#8243; img_size=&#8221;large&#8221; alignment=&#8221;center&#8221;][vc_empty_space][\/vc_column_inner][vc_column_inner width=&#8221;2\/5&#8243;][vc_column_text]La fotografia \u00e8 un lavoro d&#8217;amore e sappiamo che ogni scatto ha un peso notevole. Non lasciate che un monitor non calibrato vi impedisca di realizzare la vostra visione.<\/p>\n<p>Con Spyder X Elite, potete essere certi che ci\u00f2 che vedete sullo schermo \u00e8 la rappresentazione pi\u00f9 accurata dello scatto che avete effettuato. Quando si inizia a modificare e si sa che il colore sul monitor \u00e8 preciso, si pu\u00f2 controllare con sicurezza ogni aspetto dell&#8217;immagine. E quando \u00e8 il momento di stampare, il risultato corrisponder\u00e0 a ci\u00f2 che vedete sullo schermo e rifletter\u00e0 meglio la vostra visione creativa.[\/vc_column_text][vc_empty_space][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row bg_type=&#8221;bg_color&#8221; bg_override=&#8221;ex-full&#8221; css=&#8221;.vc_custom_1679489577173{padding-top: 30px !important;padding-bottom: 30px !important;}&#8221; bg_color_value=&#8221;#e7e6e5&#8243;][vc_column width=&#8221;1\/3&#8243;][vc_single_image image=&#8221;25805&#8243; img_size=&#8221;400&#215;280&#8243; alignment=&#8221;center&#8221;][vc_empty_space][vc_column_text]<\/p>\n<h3 style=\"margin-bottom: 15px;\">MONITORAGGIO DELLA LUCE AMBIENTALE<\/h3>\n<p>Un sensore di luce ambientale integrato misura la luce dell&#8217;ambiente durante il giorno, consentendo di regolare la luminosit\u00e0 e il contrasto del display ai livelli ideali. Il software pu\u00f2 avvisare l&#8217;utente di ricalibrare o farlo automaticamente utilizzando profili personalizzati in base al livello di luce.[\/vc_column_text][vc_empty_space][\/vc_column][vc_column width=&#8221;1\/3&#8243;][vc_single_image image=&#8221;31471&#8243; img_size=&#8221;400&#215;280&#8243; alignment=&#8221;center&#8221;][vc_empty_space][vc_column_text]<\/p>\n<h3 style=\"margin-bottom: 15px;\">MONITORARE L&#8217;ANALISI DELLE PRESTAZIONI<\/h3>\n<p>Con la funzione Analisi display, \u00e8 possibile comprendere meglio il colore, la luminosit\u00e0, il contrasto, il gamut, la risposta tonale, il punto di bianco e l&#8217;uniformit\u00e0 di visualizzazione dei monitor.[\/vc_column_text][vc_empty_space][\/vc_column][vc_column width=&#8221;1\/3&#8243;][vc_single_image image=&#8221;31481&#8243; img_size=&#8221;400&#215;280&#8243; alignment=&#8221;center&#8221;][vc_empty_space][vc_column_text]<\/p>\n<h3 style=\"margin-bottom: 15px;\">SOFTWARE INTUITIVO<\/h3>\n<p>Le modalit\u00e0 Calibrazione con un solo clic e Assistente passo-passo offrono un aiuto interattivo in ogni fase del processo.[\/vc_column_text][vc_empty_space][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1679490256333{padding-top: 30px !important;padding-bottom: 30px !important;}&#8221;][vc_column width=&#8221;2\/5&#8243;][vc_column_text]<\/p>\n<h2>Come funziona<\/h2>\n<p>La calibrazione del display ottimizza le prestazioni e la precisione dei colori del monitor per il flusso di lavoro (fotografia, videografia, ecc.). Questo processo semplice e veloce misura, valuta e corregge il display del monitor per una visione accurata del mondo digitale.<\/p>\n<p>I calibratori per monitor Spyder creano un profilo di visualizzazione ICC che viene utilizzato dalla scheda video e dal software di gestione del colore nel sistema operativo del computer. Un display calibrato consente al computer di visualizzare una rappresentazione fedele dei colori del file di immagine all&#8217;interno del software di editing, in modo da poter prendere decisioni accurate di editing per creare l&#8217;aspetto desiderato.[\/vc_column_text][vc_empty_space][\/vc_column][vc_column width=&#8221;3\/5&#8243;][vc_single_image image=&#8221;25754&#8243; img_size=&#8221;750&#215;450&#8243;][vc_empty_space][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]Spyder X Elite rende la calibrazione accurata e semplice, aiutandovi in ogni fase del processo.[\/vc_column_text][vc_empty_space][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/3&#8243;][vc_single_image image=&#8221;31491&#8243; img_size=&#8221;800&#215;600&#8243; alignment=&#8221;center&#8221;][vc_empty_space][vc_column_text]<\/p>\n<h3 style=\"margin-bottom: 15px;\">Primo passo<\/h3>\n<p>Scaricare, installare e avviare il software Spyder. Verr\u00e0 richiesto di rispondere ad alcune domande sullo schermo e sul flusso di lavoro, che verranno salvate per le calibrazioni future. [\/vc_column_text][vc_empty_space][\/vc_column][vc_column width=&#8221;1\/3&#8243;][vc_single_image image=&#8221;31501&#8243; img_size=&#8221;800&#215;600&#8243; alignment=&#8221;center&#8221;][vc_empty_space][vc_column_text]<\/p>\n<h3 style=\"margin-bottom: 15px;\">Fase due<\/h3>\n<p>Posizionare il dispositivo Spyder sul display all&#8217;interno del contorno e lasciare che il software Spyder si metta al lavoro. Eseguir\u00e0 una serie di misurazioni per costruire il profilo ICC e aiuter\u00e0 a regolare la luminosit\u00e0 dello schermo.[\/vc_column_text][vc_empty_space][\/vc_column][vc_column width=&#8221;1\/3&#8243;][vc_single_image image=&#8221;31511&#8243; img_size=&#8221;800&#215;600&#8243; alignment=&#8221;center&#8221;][vc_empty_space][vc_column_text]<\/p>\n<h3 style=\"margin-bottom: 15px;\">Terzo passo<\/h3>\n<p>Al termine delle misurazioni, rimuovere il sensore dal display e salvare il profilo che rimarr\u00e0 nel computer per essere utilizzato in futuro per questo monitor. \u00c8 sempre possibile cancellare il profilo per tornare alle impostazioni di fabbrica del monitor. [\/vc_column_text][vc_empty_space][\/vc_column][\/vc_row][vc_row disable_element=&#8221;yes&#8221; css=&#8221;.vc_custom_1682520680742{padding-top: 30px !important;padding-bottom: 30px !important;}&#8221;][vc_column][vc_column_text]<\/p>\n<h2 style=\"border-bottom: solid 1px #ccc; padding-bottom: 5px; margin-bottom: 30px;\">Videoteca<\/h2>\n<p>[\/vc_column_text][vc_empty_space]<div id=\"ult-carousel-34431794866a5758a4ca1cd\" class=\"ult-carousel-wrapper   ult_horizontal\" data-gutter=\"15\" data-rtl=\"false\" ><div class=\"ult-carousel-36287958316a5758a4ca1ae \" >[vc_row_inner][vc_column_inner][vc_single_image image=&#8221;14142&#8243; img_size=&#8221;400&#215;300&#8243; alignment=&#8221;center&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner][vc_single_image image=&#8221;14142&#8243; img_size=&#8221;400&#215;300&#8243; alignment=&#8221;center&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner][vc_single_image image=&#8221;14142&#8243; img_size=&#8221;400&#215;300&#8243; alignment=&#8221;center&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner][vc_single_image image=&#8221;14142&#8243; img_size=&#8221;400&#215;300&#8243; alignment=&#8221;center&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner][vc_single_image image=&#8221;14142&#8243; img_size=&#8221;400&#215;300&#8243; alignment=&#8221;center&#8221;][\/vc_column_inner][\/vc_row_inner]<\/div><\/div>\t\t\t<script type=\"text\/javascript\">\n\t\t\t\tjQuery(document).ready(function ($) {\n\t\t\t\t\tif( typeof jQuery('.ult-carousel-36287958316a5758a4ca1ae').slick == \"function\"){\n\t\t\t\t\t\t$('.ult-carousel-36287958316a5758a4ca1ae').slick({dots: true,autoplaySpeed: \"5000\",speed: \"300\",infinite: true,arrows: true,nextArrow: '<button type=\"button\" role=\"button\" aria-label=\"Next\" style=\"color:#333333; font-size:20px;\" class=\"slick-next default\"><i class=\"ultsl-arrow-right4\"><\/i><\/button>',prevArrow: '<button type=\"button\" role=\"button\" aria-label=\"Previous\" style=\"color:#333333; font-size:20px;\" class=\"slick-prev default\"><i class=\"ultsl-arrow-left4\"><\/i><\/button>',slidesToScroll:5,slidesToShow:5,swipe: true,draggable: true,touchMove: true,pauseOnHover: true,pauseOnFocus: false,responsive: [\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 1026,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 5,\n\t\t\t\t\t\t\t\tslidesToScroll: 5,  \n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 1025,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 3,\n\t\t\t\t\t\t\t\tslidesToScroll: 3\n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 760,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 2,\n\t\t\t\t\t\t\t\tslidesToScroll: 2\n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t}\n\t\t\t\t\t\t],pauseOnDotsHover: true,customPaging: function(slider, i) {\n                   return '<i type=\"button\" style= \"color:#333333;\" class=\"ultsl-record\" data-role=\"none\"><\/i>';\n                },});\n\t\t\t\t\t}\n\t\t\t\t});\n\t\t\t<\/script>\n\t\t\t[\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1679491516376{padding-top: 30px !important;padding-bottom: 30px !important;}&#8221;][vc_column][vc_column_text]<\/p>\n<h2 style=\"border-bottom: solid 1px #ccc; padding-bottom: 5px; margin-bottom: 30px;\">Ti potrebbe interessare anche<\/h2>\n<p>[\/vc_column_text][vc_empty_space]<div id=\"ult-carousel-37972875146a5758a4ca23d\" class=\"ult-carousel-wrapper   ult_horizontal\" data-gutter=\"15\" data-rtl=\"false\" ><div class=\"ult-carousel-860618546a5758a4ca228 \" >[vc_row_inner][vc_column_inner][vc_column_text]<div class=\"ult-item-wrap\" data-animation=\"animated no-animation\"><\/div>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner][vc_column_text]<div class=\"ult-item-wrap\" data-animation=\"animated no-animation\"><\/div>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner][vc_column_text]<div class=\"ult-item-wrap\" data-animation=\"animated no-animation\"><div class=\"vc_single_image-wrapper vc_box_border_grey\"><a href=\"\/spyder\/products\/\"><img decoding=\"async\" class=\"vc_single_image-img \" src=\"https:\/\/www.datacolor.com\/spyder\/wp-content\/uploads\/2022\/12\/Datacolor-Spyder-Cube_750x500-400x300.jpg\" width=\"400\"><\/a><\/div><a href=\"\/spyder\/products\/\"><div class=\"wpb_wrapper\"><p><strong>Spyder Cube<\/strong><br><\/p><\/div><\/a><\/div>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner][vc_column_text]<div class=\"ult-item-wrap\" data-animation=\"animated no-animation\"><div class=\"vc_single_image-wrapper vc_box_border_grey\"><a href=\"https:\/\/www.datacolor.com\/spyder\/products\/spyder-checkr-photo\/\"><img decoding=\"async\" class=\"vc_single_image-img \" src=\"https:\/\/www.datacolor.com\/spyder\/wp-content\/uploads\/2022\/08\/SpyderCheckrPhoto-Product-Image-750x500-1-400x300.jpg\" width=\"400\"><\/a><\/div><a href=\"https:\/\/www.datacolor.com\/spyder\/products\/spyder-checkr-photo\/\"><div class=\"wpb_wrapper\"><p><strong>Spyder Checkr Photo<\/strong><br><\/p><\/div><\/a><\/div>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner][vc_column_text]<div class=\"ult-item-wrap\" data-animation=\"animated no-animation\"><div class=\"vc_single_image-wrapper vc_box_border_grey\"><a href=\"\/spyder\/products\/\"><img decoding=\"async\" class=\"vc_single_image-img \" src=\"https:\/\/www.datacolor.com\/spyder\/wp-content\/uploads\/2022\/12\/SpyderShelf_15x10cm-750x500-1.jpg\" width=\"1\"><\/a><\/div><a href=\"\/spyder\/products\/\"><div class=\"wpb_wrapper\"><p><strong>Spyder Shelf<\/strong><br><\/p><\/div><\/a><\/div>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner]<\/div><\/div>\t\t\t<script type=\"text\/javascript\">\n\t\t\t\tjQuery(document).ready(function ($) {\n\t\t\t\t\tif( typeof jQuery('.ult-carousel-860618546a5758a4ca228').slick == \"function\"){\n\t\t\t\t\t\t$('.ult-carousel-860618546a5758a4ca228').slick({dots: true,autoplaySpeed: \"5000\",speed: \"300\",infinite: true,arrows: true,nextArrow: '<button type=\"button\" role=\"button\" aria-label=\"Next\" style=\"color:#333333; font-size:20px;\" class=\"slick-next default\"><i class=\"ultsl-arrow-right4\"><\/i><\/button>',prevArrow: '<button type=\"button\" role=\"button\" aria-label=\"Previous\" style=\"color:#333333; font-size:20px;\" class=\"slick-prev default\"><i class=\"ultsl-arrow-left4\"><\/i><\/button>',slidesToScroll:5,slidesToShow:5,swipe: true,draggable: true,touchMove: true,pauseOnHover: true,pauseOnFocus: false,responsive: [\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 1026,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 5,\n\t\t\t\t\t\t\t\tslidesToScroll: 5,  \n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 1025,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 3,\n\t\t\t\t\t\t\t\tslidesToScroll: 3\n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t  breakpoint: 760,\n\t\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\t\tslidesToShow: 2,\n\t\t\t\t\t\t\t\tslidesToScroll: 2\n\t\t\t\t\t\t\t  }\n\t\t\t\t\t\t\t}\n\t\t\t\t\t\t],pauseOnDotsHover: true,customPaging: function(slider, i) {\n                   return '<i type=\"button\" style= \"color:#333333;\" class=\"ultsl-record\" data-role=\"none\"><\/i>';\n                },});\n\t\t\t\t\t}\n\t\t\t\t});\n\t\t\t<\/script>\n\t\t\t[\/vc_column][\/vc_row][vc_row][vc_column][vc_raw_html]W2RjaS1zcHlkZXJhd2FyZHMgY2F0ZWdvcnk9ImRpc3BsYXktY2FsaWJyYXRpb24iIC9d[\/vc_raw_html][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column width=&#8221;3\/5&#8243;][vc_empty_space][vc_gallery interval=&#8221;3&#8243; images=&#8221;31387,31397,31407,31417,31427,31437,31447,31457&#8243; img_size=&#8221;750&#215;500&#8243; el_class=&#8221;product_images&#8221;][vc_empty_space][\/vc_column][vc_column width=&#8221;2\/5&#8243;][vc_column_text] Spyder X Elite Strumento di calibrazione del colore per monitor di editing fotografico e video con strumenti di analisi completi. Nota: non adattabile alla piattaforma Spyder X2. <div id="getprice-banner-sxe100"></div> [\/vc_column_text][vc_empty_space][vc_empty_space][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1679489540798{padding-top: 30px !important;padding-bottom: 30px !important;}&#8221;][vc_column][vc_column_text] Sappiamo che ci vuole molto per ottenere lo scatto perfetto. [\/vc_column_text][vc_empty_space][vc_row_inner][vc_column_inner width=&#8221;3\/5&#8243;][vc_single_image image=&#8221;14200&#8243; img_size=&#8221;large&#8221; &hellip;<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":24739,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-33509","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.datacolor.com\/spyder\/it\/wp-json\/wp\/v2\/pages\/33509","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.datacolor.com\/spyder\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.datacolor.com\/spyder\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.datacolor.com\/spyder\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.datacolor.com\/spyder\/it\/wp-json\/wp\/v2\/comments?post=33509"}],"version-history":[{"count":0,"href":"https:\/\/www.datacolor.com\/spyder\/it\/wp-json\/wp\/v2\/pages\/33509\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.datacolor.com\/spyder\/it\/wp-json\/wp\/v2\/pages\/24739"}],"wp:attachment":[{"href":"https:\/\/www.datacolor.com\/spyder\/it\/wp-json\/wp\/v2\/media?parent=33509"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}